{"id":121,"count":10,"description":"","link":"https:\/\/www.elturistatranquil.com\/ca\/categoria\/a-coruna-ca-2\/","name":"A Coru\u00f1a","slug":"a-coruna-ca-2","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Coru\u00f1a - El turista tranquil<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Coru\u00f1a - El turista tranquil\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elturistatranquil.com\/ca\/categoria\/a-coruna-ca-2\/\" \/>\n<meta property=\"og:site_name\" content=\"El turista tranquil\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.elturistatranquil.com\\\/ca\\\/categoria\\\/a-coruna-ca-2\\\/\",\"url\":\"https:\\\/\\\/www.elturistatranquil.com\\\/ca\\\/categoria\\\/a-coruna-ca-2\\\/\",\"name\":\"A Coru\u00f1a - El turista tranquil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elturistatranquil.com\\\/ca\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elturistatranquil.com\\\/ca\\\/categoria\\\/a-coruna-ca-2\\\/#breadcrumb\"},\"inLanguage\":\"ca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elturistatranquil.com\\\/ca\\\/categoria\\\/a-coruna-ca-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.elturistatranquil.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Coru\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elturistatranquil.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.elturistatranquil.com\\\/ca\\\/\",\"name\":\"El turista tranquil\",\"description\":\"Blog de viatges\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.elturistatranquil.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Coru\u00f1a - El turista tranquil","robots":{"index":"noindex","follow":"follow"},"og_locale":"ca_ES","og_type":"article","og_title":"A Coru\u00f1a - El turista tranquil","og_url":"https:\/\/www.elturistatranquil.com\/ca\/categoria\/a-coruna-ca-2\/","og_site_name":"El turista tranquil","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.elturistatranquil.com\/ca\/categoria\/a-coruna-ca-2\/","url":"https:\/\/www.elturistatranquil.com\/ca\/categoria\/a-coruna-ca-2\/","name":"A Coru\u00f1a - El turista tranquil","isPartOf":{"@id":"https:\/\/www.elturistatranquil.com\/ca\/#website"},"breadcrumb":{"@id":"https:\/\/www.elturistatranquil.com\/ca\/categoria\/a-coruna-ca-2\/#breadcrumb"},"inLanguage":"ca"},{"@type":"BreadcrumbList","@id":"https:\/\/www.elturistatranquil.com\/ca\/categoria\/a-coruna-ca-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.elturistatranquil.com\/ca\/"},{"@type":"ListItem","position":2,"name":"A Coru\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/www.elturistatranquil.com\/ca\/#website","url":"https:\/\/www.elturistatranquil.com\/ca\/","name":"El turista tranquil","description":"Blog de viatges","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elturistatranquil.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/www.elturistatranquil.com\/ca\/wp-json\/wp\/v2\/categories\/121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elturistatranquil.com\/ca\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.elturistatranquil.com\/ca\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.elturistatranquil.com\/ca\/wp-json\/wp\/v2\/posts?categories=121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}